{"id":1970,"date":"2025-12-20T15:17:40","date_gmt":"2025-12-20T08:17:40","guid":{"rendered":"https:\/\/gs.mbuisc.ac.th\/th\/?p=1970"},"modified":"2025-12-20T15:26:17","modified_gmt":"2025-12-20T08:26:17","slug":"%e0%b8%90%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b9%80%e0%b8%97%e0%b8%a8-%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%99","status":"publish","type":"post","link":"https:\/\/gs.mbuisc.ac.th\/th\/%e0%b8%90%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b9%80%e0%b8%97%e0%b8%a8-%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%99\/","title":{"rendered":"\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e19\u0e35\u0e22\u0e1a\u0e31\u0e15\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e04\u0e23\u0e39 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2568"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1970\" class=\"elementor elementor-1970\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4886a87 e-flex e-con-boxed e-con e-parent\" data-id=\"4886a87\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f1092b elementor-widget elementor-widget-image\" data-id=\"9f1092b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28-\u0e1b.\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15-1024x512.png\" class=\"attachment-large size-large wp-image-1971\" alt=\"\" srcset=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28-\u0e1b.\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15-1024x512.png 1024w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28-\u0e1b.\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15-300x150.png 300w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28-\u0e1b.\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15-768x384.png 768w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28-\u0e1b.\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15-1536x768.png 1536w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28-\u0e1b.\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15-2048x1024.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e5867b e-flex e-con-boxed e-con e-parent\" data-id=\"2e5867b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-16a06e3 elementor-widget elementor-widget-text-editor\" data-id=\"16a06e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e32\u0e21\u0e01\u0e38\u0e0f\u0e23\u0e32\u0e0a\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e2d\u0e35\u0e2a\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e19\u0e35\u0e22\u0e1a\u0e31\u0e15\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e04\u0e23\u0e39 \u0e1b.\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e13 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e0a\u0e31\u0e49\u0e19 2 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1e\u0e23\u0e30\u0e2a\u0e38\u0e18\u0e35\u0e27\u0e0a\u0e34\u0e23\u0e18\u0e23\u0e23\u0e21 \u0e1c\u0e28.\u0e14\u0e23. \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19 \u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e28\u0e38\u0e20\u0e0a\u0e31\u0e22 \u0e2a\u0e38\u0e20\u0e01\u0e34\u0e08\u0e3a\u0e42\u0e08 \u0e23\u0e28.\u0e14\u0e23. \u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e27\u0e32\u0e22\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e08\u0e32\u0e01\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u00a0<br \/>\u0e20\u0e32\u0e1e : \u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e20\u0e32\u0e1e<br \/>\u0e02\u0e48\u0e32\u0e27 : \u0e19\u0e34\u0e27\u0e31\u0e12\u0e19\u0e32<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-244bce3 e-grid e-con-boxed e-con e-parent\" data-id=\"244bce3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-072dd66 elementor-widget elementor-widget-image\" data-id=\"072dd66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/599946782_1366074341976034_8584799724514327165_n-1024x683.jpg\" class=\"attachment-large size-large wp-image-1973\" alt=\"\" srcset=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/599946782_1366074341976034_8584799724514327165_n-1024x683.jpg 1024w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/599946782_1366074341976034_8584799724514327165_n-300x200.jpg 300w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/599946782_1366074341976034_8584799724514327165_n-768x512.jpg 768w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/599946782_1366074341976034_8584799724514327165_n-1536x1024.jpg 1536w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/599946782_1366074341976034_8584799724514327165_n-930x620.jpg 930w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/599946782_1366074341976034_8584799724514327165_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-946b14b elementor-widget elementor-widget-image\" data-id=\"946b14b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600436239_1366074001976068_4308822107644239913_n-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-1984\" alt=\"\" srcset=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600436239_1366074001976068_4308822107644239913_n-1-1024x683.jpg 1024w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600436239_1366074001976068_4308822107644239913_n-1-300x200.jpg 300w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600436239_1366074001976068_4308822107644239913_n-1-768x512.jpg 768w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600436239_1366074001976068_4308822107644239913_n-1-1536x1024.jpg 1536w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600436239_1366074001976068_4308822107644239913_n-1-930x620.jpg 930w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600436239_1366074001976068_4308822107644239913_n-1.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e667db e-grid e-con-boxed e-con e-parent\" data-id=\"7e667db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc0cde0 elementor-widget elementor-widget-image\" data-id=\"fc0cde0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/603798963_1366074465309355_6414208379597009970_n-1024x683.jpg\" class=\"attachment-large size-large wp-image-1986\" alt=\"\" srcset=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/603798963_1366074465309355_6414208379597009970_n-1024x683.jpg 1024w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/603798963_1366074465309355_6414208379597009970_n-300x200.jpg 300w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/603798963_1366074465309355_6414208379597009970_n-768x512.jpg 768w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/603798963_1366074465309355_6414208379597009970_n-1536x1024.jpg 1536w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/603798963_1366074465309355_6414208379597009970_n-930x620.jpg 930w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/603798963_1366074465309355_6414208379597009970_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8228e0 elementor-widget elementor-widget-image\" data-id=\"d8228e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600309175_1366074325309369_537980798426198140_n-1024x683.jpg\" class=\"attachment-large size-large wp-image-1980\" alt=\"\" srcset=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600309175_1366074325309369_537980798426198140_n-1024x683.jpg 1024w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600309175_1366074325309369_537980798426198140_n-300x200.jpg 300w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600309175_1366074325309369_537980798426198140_n-768x512.jpg 768w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600309175_1366074325309369_537980798426198140_n-1536x1024.jpg 1536w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600309175_1366074325309369_537980798426198140_n-930x620.jpg 930w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600309175_1366074325309369_537980798426198140_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99b704d e-grid e-con-boxed e-con e-parent\" data-id=\"99b704d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-159d8da elementor-widget elementor-widget-image\" data-id=\"159d8da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600363954_1366074108642724_2169551388441057616_n-1024x683.jpg\" class=\"attachment-large size-large wp-image-1982\" alt=\"\" srcset=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600363954_1366074108642724_2169551388441057616_n-1024x683.jpg 1024w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600363954_1366074108642724_2169551388441057616_n-300x200.jpg 300w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600363954_1366074108642724_2169551388441057616_n-768x512.jpg 768w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600363954_1366074108642724_2169551388441057616_n-1536x1024.jpg 1536w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600363954_1366074108642724_2169551388441057616_n-930x620.jpg 930w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600363954_1366074108642724_2169551388441057616_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e541586 elementor-widget elementor-widget-image\" data-id=\"e541586\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600330043_1366074081976060_3712170351070347706_n-1024x683.jpg\" class=\"attachment-large size-large wp-image-1981\" alt=\"\" srcset=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600330043_1366074081976060_3712170351070347706_n-1024x683.jpg 1024w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600330043_1366074081976060_3712170351070347706_n-300x200.jpg 300w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600330043_1366074081976060_3712170351070347706_n-768x512.jpg 768w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600330043_1366074081976060_3712170351070347706_n-1536x1024.jpg 1536w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600330043_1366074081976060_3712170351070347706_n-930x620.jpg 930w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600330043_1366074081976060_3712170351070347706_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7244d2 elementor-widget elementor-widget-image\" data-id=\"f7244d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600449975_1366074148642720_2494738762480130251_n-1024x683.jpg\" class=\"attachment-large size-large wp-image-1985\" alt=\"\" srcset=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600449975_1366074148642720_2494738762480130251_n-1024x683.jpg 1024w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600449975_1366074148642720_2494738762480130251_n-300x200.jpg 300w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600449975_1366074148642720_2494738762480130251_n-768x512.jpg 768w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600449975_1366074148642720_2494738762480130251_n-1536x1024.jpg 1536w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600449975_1366074148642720_2494738762480130251_n-930x620.jpg 930w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600449975_1366074148642720_2494738762480130251_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dadea7b elementor-widget elementor-widget-image\" data-id=\"dadea7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/599711259_1366074128642722_2739216810201296916_n-1024x683.jpg\" class=\"attachment-large size-large wp-image-1975\" alt=\"\" srcset=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/599711259_1366074128642722_2739216810201296916_n-1024x683.jpg 1024w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/599711259_1366074128642722_2739216810201296916_n-300x200.jpg 300w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/599711259_1366074128642722_2739216810201296916_n-768x512.jpg 768w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/599711259_1366074128642722_2739216810201296916_n-1536x1024.jpg 1536w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/599711259_1366074128642722_2739216810201296916_n-930x620.jpg 930w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/599711259_1366074128642722_2739216810201296916_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-629d5b3 e-grid e-con-boxed e-con e-parent\" data-id=\"629d5b3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23c93a8 elementor-widget elementor-widget-image\" data-id=\"23c93a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600285309_1366074701975998_2491438664949930784_n-1024x683.jpg\" class=\"attachment-large size-large wp-image-1979\" alt=\"\" srcset=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600285309_1366074701975998_2491438664949930784_n-1024x683.jpg 1024w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600285309_1366074701975998_2491438664949930784_n-300x200.jpg 300w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600285309_1366074701975998_2491438664949930784_n-768x512.jpg 768w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600285309_1366074701975998_2491438664949930784_n-1536x1024.jpg 1536w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600285309_1366074701975998_2491438664949930784_n-930x620.jpg 930w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600285309_1366074701975998_2491438664949930784_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b08f4a elementor-widget elementor-widget-image\" data-id=\"8b08f4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600276146_1366074045309397_1454546139038100748_n-1024x683.jpg\" class=\"attachment-large size-large wp-image-1978\" alt=\"\" srcset=\"https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600276146_1366074045309397_1454546139038100748_n-1024x683.jpg 1024w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600276146_1366074045309397_1454546139038100748_n-300x200.jpg 300w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600276146_1366074045309397_1454546139038100748_n-768x512.jpg 768w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600276146_1366074045309397_1454546139038100748_n-1536x1024.jpg 1536w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600276146_1366074045309397_1454546139038100748_n-930x620.jpg 930w, https:\/\/gs.mbuisc.ac.th\/th\/wp-content\/uploads\/2025\/12\/600276146_1366074045309397_1454546139038100748_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e32\u0e21\u0e01\u0e38\u0e0f\u0e23\u0e32\u0e0a\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e2d\u0e35\u0e2a\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e19\u0e35\u0e22\u0e1a\u0e31\u0e15\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e04\u0e23\u0e39 \u0e1b.\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e13 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e0a\u0e31\u0e49\u0e19 2 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1e\u0e23\u0e30\u0e2a\u0e38\u0e18\u0e35\u0e27\u0e0a\u0e34\u0e23\u0e18\u0e23\u0e23\u0e21 \u0e1c\u0e28.\u0e14\u0e23. \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19 \u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e28\u0e38\u0e20\u0e0a\u0e31\u0e22 \u0e2a\u0e38\u0e20\u0e01\u0e34\u0e08\u0e3a\u0e42\u0e08 \u0e23\u0e28.\u0e14\u0e23. \u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e27\u0e32\u0e22\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e08\u0e32\u0e01\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u00a0\u0e20\u0e32\u0e1e : \u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e20\u0e32\u0e1e\u0e02\u0e48\u0e32\u0e27 : \u0e19\u0e34\u0e27\u0e31\u0e12\u0e19\u0e32<\/p>\n","protected":false},"author":1,"featured_media":1971,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-1970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gs-mbuisc-news"],"_links":{"self":[{"href":"https:\/\/gs.mbuisc.ac.th\/th\/wp-json\/wp\/v2\/posts\/1970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gs.mbuisc.ac.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gs.mbuisc.ac.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gs.mbuisc.ac.th\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gs.mbuisc.ac.th\/th\/wp-json\/wp\/v2\/comments?post=1970"}],"version-history":[{"count":5,"href":"https:\/\/gs.mbuisc.ac.th\/th\/wp-json\/wp\/v2\/posts\/1970\/revisions"}],"predecessor-version":[{"id":1990,"href":"https:\/\/gs.mbuisc.ac.th\/th\/wp-json\/wp\/v2\/posts\/1970\/revisions\/1990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gs.mbuisc.ac.th\/th\/wp-json\/wp\/v2\/media\/1971"}],"wp:attachment":[{"href":"https:\/\/gs.mbuisc.ac.th\/th\/wp-json\/wp\/v2\/media?parent=1970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gs.mbuisc.ac.th\/th\/wp-json\/wp\/v2\/categories?post=1970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gs.mbuisc.ac.th\/th\/wp-json\/wp\/v2\/tags?post=1970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}